{"id":197823,"date":"2022-07-19T12:09:04","date_gmt":"2022-07-19T12:09:04","guid":{"rendered":"https:\/\/www.liveu.tv\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows"},"modified":"2022-07-19T12:14:15","modified_gmt":"2022-07-19T12:14:15","slug":"liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","status":"publish","type":"press_release","link":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","title":{"rendered":"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube"},"content":{"rendered":"\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"538\" src=\"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES-1024x538.png\" alt=\"\" class=\"wp-image-197832\" srcset=\"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES-1024x538.png 1024w, https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES-300x158.png 300w, https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES-768x403.png 768w, https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png 1200w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<h2 class=\"wp-block-heading\" style=\"font-size:24px\">LiveU ha ampliado su equipo espa\u00f1ol y ha abierto una nueva oficina en Madrid para satisfacer los requisitos cada vez mayores de los clientes locales nuevos y existentes<\/h2>\n\n\n\n<p>En respuesta a una demanda cada vez mayor en Espa\u00f1a, y para servir mejor a una creciente gama de requisitos, LiveU ha ampliado su presencia local en el pa\u00eds. La compa\u00f1\u00eda ha abierto una nueva oficina en Madrid, junto con una presencia en Barcelona, y ha nombrado a Laura Llames como Country Manager.<\/p>\n\n\n\n<p>Zion Eilam, Vicepresidente Regional de Ventas, EMEA, LiveU, dijo: \"Estar m\u00e1s cerca de nuestros clientes en los mercados clave es una prioridad para LiveU. La proximidad geogr\u00e1fica nos permite responder a\u00fan m\u00e1s r\u00e1pido y ofrecer soluciones localizadas con una experiencia m\u00e1s personalizada en las ventas y el soporte t\u00e9cnico in situ. Es un momento enormemente emocionante para la empresa y es vital que llevemos a nuestros clientes con nosotros.\"<\/p>\n\n\n\n<p>Al ampliar su equipo local con el nombramiento de Laura Llames, LiveU puede trabajar m\u00e1s estrechamente con los clientes y partners espa\u00f1oles, hablando, literal y t\u00e9cnicamente, su idioma.<\/p>\n\n\n\n<p>Laura Llames se incorpora desde MediaPro, reconocido integrador de soluciones de contenido, producci\u00f3n y distribuci\u00f3n audiovisual con sede en Espa\u00f1a. All\u00ed ejerc\u00eda profesionalmente de Directora Comercial de la LVP (Liga de Videojuegos Profesional) de MediaPro en Espa\u00f1a. Laura cuenta con una amplia experiencia en ventas y tecnolog\u00eda gracias a sus anteriores funciones. Adem\u00e1s, cuenta con el apoyo de un equipo ampliado de ventas y soporte t\u00e9cnico en Madrid y Barcelona para aumentar a\u00fan m\u00e1s el alcance local de LiveU.<\/p>\n\n\n\n<p>Laura Llames dijo: \"Estoy muy emocionada de trabajar con LiveU. La empresa busca constantemente formas de ampliar su presencia local y con el crecimiento que estamos experimentando en el pa\u00eds, y la naturaleza diversa de nuestros clientes y sus requisitos, es esencial que podamos satisfacer sus necesidades, de forma r\u00e1pida y precisa. Nuestras puertas est\u00e1n abiertas para nuestros clientes; ya sea en las noticias, los deportes u otros verticales como la seguridad p\u00fablica o la educaci\u00f3n, todos est\u00e1n interesados en ver nuestra tecnolog\u00eda de v\u00eddeo en directo de primera mano.\"<\/p>\n\n\n\n<p>Zion Eilam a\u00f1adi\u00f3: \"Espa\u00f1a ha sido un mercado muy exitoso para LiveU y es un mercado que sigue creciendo, tanto por el n\u00famero de clientes con los que trabajamos como por la creciente gama de soluciones LiveU que los clientes nos piden desplegar. \u00c9stas, van de la mano de nuestros servicios basados en la nube en expansi\u00f3n y de nuestra gama de soluciones de transmisi\u00f3n de enlace IP 5G en continua actualizaci\u00f3n.\"<\/p>\n","protected":false},"excerpt":{"rendered":"<p>July 19<\/p>\n","protected":false},"author":8,"featured_media":197832,"template":"","post_tag":[],"class_list":["post-197823","press_release","type-press_release","status-publish","has-post-thumbnail","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO Premium plugin v27.4 (Yoast SEO v27.4) - https:\/\/yoast.com\/product\/yoast-seo-premium-wordpress\/ -->\n<title>LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube - LiveU<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows\" \/>\n<meta property=\"og:locale\" content=\"es_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube\" \/>\n<meta property=\"og:description\" content=\"July 19\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows\" \/>\n<meta property=\"og:site_name\" content=\"LiveU\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/LiveU.Fans\" \/>\n<meta property=\"article:modified_time\" content=\"2022-07-19T12:14:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"630\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@LiveU\" \/>\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutos\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows\",\"url\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows\",\"name\":\"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube - LiveU\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.liveu.tv\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Spainish-Office-Announcemnet_ES.png\",\"datePublished\":\"2022-07-19T12:09:04+00:00\",\"dateModified\":\"2022-07-19T12:14:15+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage\",\"url\":\"https:\\\/\\\/www.liveu.tv\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Spainish-Office-Announcemnet_ES.png\",\"contentUrl\":\"https:\\\/\\\/www.liveu.tv\\\/wp-content\\\/uploads\\\/2022\\\/07\\\/Spainish-Office-Announcemnet_ES.png\",\"width\":1200,\"height\":630},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\\\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"LiveU\",\"item\":\"https:\\\/\\\/www.liveu.tv\\\/es\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Press Releases\",\"item\":\"https:\\\/\\\/www.liveu.tv\\\/es\\\/company\\\/press-releases\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#website\",\"url\":\"https:\\\/\\\/www.liveu.tv\\\/es\",\"name\":\"LiveU\",\"description\":\"LiveU&#039;s Corporate Website\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.liveu.tv\\\/es?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#organization\",\"name\":\"LIVEU\",\"url\":\"https:\\\/\\\/www.liveu.tv\\\/es\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.liveu.tv\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/LiveU_Logo_On_Whtite.png\",\"contentUrl\":\"https:\\\/\\\/www.liveu.tv\\\/wp-content\\\/uploads\\\/2021\\\/06\\\/LiveU_Logo_On_Whtite.png\",\"width\":924,\"height\":313,\"caption\":\"LIVEU\"},\"image\":{\"@id\":\"https:\\\/\\\/www.liveu.tv\\\/es#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/LiveU.Fans\",\"https:\\\/\\\/x.com\\\/LiveU\",\"https:\\\/\\\/www.instagram.com\\\/liveutv\\\/\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/liveu\",\"https:\\\/\\\/www.youtube.com\\\/user\\\/liveUtv\"]}]}<\/script>\n<!-- \/ Yoast SEO Premium plugin. -->","yoast_head_json":{"title":"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube - LiveU","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","og_locale":"es_ES","og_type":"article","og_title":"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube","og_description":"July 19","og_url":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","og_site_name":"LiveU","article_publisher":"https:\/\/www.facebook.com\/LiveU.Fans","article_modified_time":"2022-07-19T12:14:15+00:00","og_image":[{"width":1200,"height":630,"url":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@LiveU","twitter_misc":{"Tiempo de lectura":"3 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","url":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows","name":"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube - LiveU","isPartOf":{"@id":"https:\/\/www.liveu.tv\/es#website"},"primaryImageOfPage":{"@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage"},"image":{"@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage"},"thumbnailUrl":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png","datePublished":"2022-07-19T12:09:04+00:00","dateModified":"2022-07-19T12:14:15+00:00","breadcrumb":{"@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#primaryimage","url":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png","contentUrl":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2022\/07\/Spainish-Office-Announcemnet_ES.png","width":1200,"height":630},{"@type":"BreadcrumbList","@id":"https:\/\/www.liveu.tv\/es\/company\/press-releases\/liveu-strengthens-its-presence-in-spain-as-local-demand-for-its-video-solutions-and-cloud-services-grows#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"LiveU","item":"https:\/\/www.liveu.tv\/es"},{"@type":"ListItem","position":2,"name":"Press Releases","item":"https:\/\/www.liveu.tv\/es\/company\/press-releases"},{"@type":"ListItem","position":3,"name":"LiveU refuerza su presencia en Espa\u00f1a mientras crece la demanda local de sus soluciones de v\u00eddeo y servicios en la nube"}]},{"@type":"WebSite","@id":"https:\/\/www.liveu.tv\/es#website","url":"https:\/\/www.liveu.tv\/es","name":"LiveU","description":"LiveU&#039;s Corporate Website","publisher":{"@id":"https:\/\/www.liveu.tv\/es#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.liveu.tv\/es?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.liveu.tv\/es#organization","name":"LIVEU","url":"https:\/\/www.liveu.tv\/es","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.liveu.tv\/es#\/schema\/logo\/image\/","url":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2021\/06\/LiveU_Logo_On_Whtite.png","contentUrl":"https:\/\/www.liveu.tv\/wp-content\/uploads\/2021\/06\/LiveU_Logo_On_Whtite.png","width":924,"height":313,"caption":"LIVEU"},"image":{"@id":"https:\/\/www.liveu.tv\/es#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/LiveU.Fans","https:\/\/x.com\/LiveU","https:\/\/www.instagram.com\/liveutv\/","https:\/\/www.linkedin.com\/company\/liveu","https:\/\/www.youtube.com\/user\/liveUtv"]}]}},"_links":{"self":[{"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/press_release\/197823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/press_release"}],"about":[{"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/types\/press_release"}],"author":[{"embeddable":true,"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/users\/8"}],"version-history":[{"count":1,"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/press_release\/197823\/revisions"}],"predecessor-version":[{"id":197838,"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/press_release\/197823\/revisions\/197838"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/media\/197832"}],"wp:attachment":[{"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/media?parent=197823"}],"wp:term":[{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.liveu.tv\/es\/wp-json\/wp\/v2\/post_tag?post=197823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}